{"id":2409,"date":"2023-09-28T15:55:06","date_gmt":"2023-09-28T13:55:06","guid":{"rendered":"http:\/\/otmfqun.cluster030.hosting.ovh.net\/kkk-commits-to-a-new-of-sterilisation\/"},"modified":"2023-09-05T10:18:04","modified_gmt":"2023-09-05T08:18:04","slug":"kkk-commits-to-a-new-of-sterilisation","status":"publish","type":"post","link":"https:\/\/www.hydrolock-sterilizers.com\/es\/kkk-commits-to-a-new-of-sterilisation\/","title":{"rendered":"KKK APUESTA POR UNA NUEVA FORMA DE ESTERILIZACI\u00d3N"},"content":{"rendered":"<p>Estimados, soy Evegniya Bukur, Directora de Proyectos e Importaciones en KKK (Konservery Kombinar en Krasnodar). Somos productores de ma\u00edz y guisantes desde hace m\u00e1s de 20 a\u00f1os.<\/p>\n<p>En 2020, hab\u00edamos decidido invertir en nuevas l\u00edneas para guisantes y ma\u00edz dulce al vac\u00edo, con esterilizador continuo en lugar de por lotes.<\/p>\n<p>2 jugadores est\u00e1n en el mercado para tal m\u00e1quina, despu\u00e9s de un fuerte an\u00e1lisis de cada uno, hab\u00edamos decidido trabajar con Hydrolock como para nosotros son:<\/p>\n<p>La m\u00e1s flexible<br \/>\nLa m\u00e1s rentable en t\u00e9rminos de mantenimiento y energ\u00eda<br \/>\nEl plazo de entrega m\u00e1s corto<br \/>\nEl equipo est\u00e1 realmente disponible<\/p>\n<p>Pedimos un esterilizador de 800 latas por minuto en septiembre de 2020, la m\u00e1quina se entreg\u00f3 a finales de marzo de 2021 y estuvo lista para funcionar a m\u00e1xima capacidad desde mediados de mayo de 2021 hasta mediados de noviembre.<\/p>\n<p>Despu\u00e9s de una temporada de experiencia podemos decir que estamos muy satisfechos con el esterilizador Hydrolock, satisface plenamente nuestras necesidades. Tambi\u00e9n estamos muy satisfechos con los servicios de Hydrolock, el equipo siempre est\u00e1 disponible por conexi\u00f3n remota cuando es necesario, y por ejemplo, un t\u00e9cnico vino (gratis) 2 semanas antes de la segunda temporada, para echar un vistazo a la m\u00e1quina y asegurarse de que todo estar\u00e1 bien para la nueva temporada.<\/p>\n<p>Puede trabajar con Hydrolock, no habr\u00e1 ninguna sorpresa.<\/p>\n<p>En comparaci\u00f3n con la competencia, la m\u00e1quina Hydrolock es m\u00e1s compacta y no requiere una preparaci\u00f3n especial en el dise\u00f1o del edificio.<\/p>\n<p>Tambi\u00e9n como decidimos comprar esta m\u00e1quina sobre todo para el ma\u00edz dulce &#8211; cosa muy importante era la rotaci\u00f3n constante del producto que permite obtener un ma\u00edz dulce al vac\u00edo de alta calidad (cuello amarillo brillante y granos crujientes).<\/p>\n<p>No hemos tenido ning\u00fan problema con los comentarios de Hydrolock, empezando por los consejos de funcionamiento y terminando con las preguntas t\u00e9cnicas.<\/p>\n<p>&nbsp;<\/p>\n<p>Saludos cordiales,<\/p>\n<p>Evegniya Bukur,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimados, soy Evegniya Bukur, Directora de Proyectos e Importaciones en KKK (Konservery&#8230; <br \/><a class=\"readmore\" href=\"https:\/\/www.hydrolock-sterilizers.com\/es\/kkk-commits-to-a-new-of-sterilisation\/\"><\/a><\/p>\n","protected":false},"author":2,"featured_media":2332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105],"tags":[],"class_list":["post-2409","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-testimonios"],"_links":{"self":[{"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/posts\/2409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/comments?post=2409"}],"version-history":[{"count":2,"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/posts\/2409\/revisions"}],"predecessor-version":[{"id":2414,"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/posts\/2409\/revisions\/2414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/media\/2332"}],"wp:attachment":[{"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/media?parent=2409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/categories?post=2409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hydrolock-sterilizers.com\/es\/wp-json\/wp\/v2\/tags?post=2409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}